{"id":21226,"date":"2016-04-29T00:00:00","date_gmt":"2016-04-29T00:00:00","guid":{"rendered":"https:\/\/www.azureazure.com\/sin-categorizar\/estilograficas-de-lujo-nakaya-solo-para-su-mano"},"modified":"2019-11-12T08:29:24","modified_gmt":"2019-11-12T13:29:24","slug":"plumas-nakaya","status":"publish","type":"post","link":"https:\/\/www.azureazure.com\/es\/regalos\/plumas-nakaya\/","title":{"rendered":"Estilogr\u00e1ficas de lujo Nakaya: \u201cS\u00f3lo para su mano\u201d"},"content":{"rendered":"<div id=\"Body_MasterContent_element_2620_BodyFieldHolder\">\n<article>\n<p><img decoding=\"async\" class=\"img-responsive\" alt=\"\" src=\"\/files\/Images\/Bulletins\/SpecialToys\/nakaya-pens\/Artboard%2010.jpg\"><\/p>\n<p><span style=\"color: rgb(102, 102, 102); line-height: 22px; font-family: georgia; font-size: 15px;\"><strong><a href=\"http:\/\/www.nakaya.org\/en\/\" target=\"_blank\" rel=\"noopener noreferrer\">Nakaya<\/a><\/strong>, el fabricante de estilogr\u00e1ficas, usa la frase \u201cS\u00f3lo para su mano\u201d como lema, y no podr\u00eda sonar m\u00e1s apropiado.<\/span><\/p>\n<p><span style=\"color: rgb(102, 102, 102); line-height: 22px; font-family: georgia; font-size: 15px;\">El fabricante japon\u00e9s de lapiceras de lujo, o plumas, como tambi\u00e9n se les conoce, ha venido fabricando productos de calidad desde sus inicios en 1919 como la Platinum Pen Company.<\/span><\/p>\n<p><span style=\"color: rgb(102, 102, 102); line-height: 22px; font-family: georgia; font-size: 15px;\">Las plumas de fuente usan como material base ebonita, y son revestidas luego con capas de laca Urushi.<\/span><\/p>\n<p><span style=\"color: rgb(102, 102, 102); line-height: 22px; font-family: georgia; font-size: 15px;\">Los plumines<strong> Nakaya<\/strong> de oro s\u00f3lido de 14 quilates se destacan por sus excepcionales cualidades de escritura. Cada estilogr\u00e1fica Nakaya requiere un m\u00ednimo de tres a seis meses para su fabricaci\u00f3n.<\/span><\/p>\n<p><span style=\"color: rgb(102, 102, 102); line-height: 22px; font-family: georgia; font-size: 15px;\">El nombre de Nakaya es sin\u00f3nimo de calidad superior. El presidente de la compa\u00f1\u00eda, <strong>Nakata Toshiya, <\/strong>dice que la misi\u00f3n de  Nakaya es una sola: \u201cDise\u00f1ar un lapicero perfecto para su mano, y s\u00f3lo para su mano\u00bb.<\/span><\/p>\n<p><span style=\"color: rgb(102, 102, 102); line-height: 22px; font-family: georgia; font-size: 15px;\"><img decoding=\"async\" class=\"img-responsive\" alt=\"\" src=\"\/files\/Images\/Bulletins\/SpecialToys\/nakaya-pens\/Artboard%209.jpg\"><\/p>\n<p>Y sin dudas las plumas estilogr\u00e1ficas Nakaya son bastante excepcionales. No s\u00f3lo va a sentir la diferencia en la textura de cada pluma hecha a mano, sino que su atractivo visual es impresionante. Cada una de ellas es una obra de arte.<\/span><\/p>\n<p><span style=\"color: rgb(102, 102, 102); line-height: 22px; font-family: georgia; font-size: 15px;\">La atenci\u00f3n al detalle proviene de la experiencia de los artesanos de Nakaya, que han dedicado su vida a la creaci\u00f3n de estas sorprendentes herramientas de escritura. De acuerdo con el presidente de la compa\u00f1\u00eda, los maestros artesanos de la f\u00e1brica Platinum han organizado seminarios itinerantes en muchos grandes almacenes y tiendas de instrumentos de escritura en todo Jap\u00f3n a lo largo de los a\u00f1os.<\/span><\/p>\n<p><span style=\"color: rgb(102, 102, 102); line-height: 22px; font-family: georgia; font-size: 15px;\">Los cuerpos y plumillas se crean en Tokio, mientras que el lacado Urushi se realiza en la regi\u00f3n de Wajima, en la costa oeste de Jap\u00f3n. Los productos de la l\u00ednea Makie se realizan tanto en Wajima como en el taller de Nakaya en Tokio.<\/span><\/p>\n<p><span style=\"color: rgb(102, 102, 102); line-height: 22px; font-family: georgia; font-size: 15px;\">Gracias a Internet, se pueden apreciar hoy en todo el mundo todas las plumas estilogr\u00e1ficasNakaya. De hecho, la compa\u00f1\u00eda ha presentado recientemente cinco nuevos modelos.<\/span><\/p>\n<p><span style=\"color: rgb(102, 102, 102); line-height: 22px; font-family: georgia; font-size: 15px;\">A continuaci\u00f3n les presentamos un resumen de cada uno.<\/span><\/p>\n<p><span style=\"color: rgb(102, 102, 102); line-height: 22px; font-family: georgia; font-size: 15px;\"><strong><a href=\"http:\/\/nakaya.org\/en\/review.aspx?id=416&#038;type=body\" target=\"_blank\" rel=\"noopener noreferrer\">Makie Daimyo Procession<\/a><\/strong>.  Precio: US$ 10,000<\/span><\/p>\n<p><span style=\"color: rgb(102, 102, 102); line-height: 22px; font-family: georgia; font-size: 15px;\">El Makie incorpora un dise\u00f1o muy detallado de esta tradicional procesi\u00f3n japonesa, delineada en 150 mm de longitud. Contiene minuciosos detalles hechos a mano y grabados en oro, y la base viene en forma de cigarro.<\/span><\/p>\n<p><span style=\"color: rgb(102, 102, 102); line-height: 22px; font-family: georgia; font-size: 15px;\"><strong><a href=\"http:\/\/nakaya.org\/en\/order_form.aspx?body=415\" target=\"_blank\" rel=\"noopener noreferrer\">Soga Shouhaku \/ Unryu-zu<\/a><\/strong>.  Precio: US$ 5,000<\/span><\/p>\n<p><span style=\"color: rgb(102, 102, 102); line-height: 22px; font-family: georgia; font-size: 15px;\">La compa\u00f1\u00eda cre\u00f3 un <em>Makie de Unryu-zu<\/em>, basada en una obra maestra de <strong>Soga Shouhaku<\/strong>, artista de mediados del per\u00edodo Edo. La pintura original, guardada en el Museo de Bellas Artes de Boston, est\u00e1 pintada en ocho paneles plegables, de los cuales cuatro han sido incorporados al motivo de la pluma.<\/span><\/p>\n<p><span style=\"color: rgb(102, 102, 102); line-height: 22px; font-family: georgia; font-size: 15px;\"><strong>Sakura Sakura.<\/strong>   Precio : $ 1,970<\/span><\/p>\n<p><span style=\"color: rgb(102, 102, 102); line-height: 22px; font-family: georgia; font-size: 15px;\">Este modelo fue creado como un regalo para la hija de un cliente que ten\u00eda pasi\u00f3n por la m\u00fasica. El tema de apertura de una canci\u00f3n popular japonesa \u00abSakura Sakura\u201d (\u201cflores de cerezo, flores de cerezo)\u00bb est\u00e1 grabado en todo el cuerpo de la estilogr\u00e1fica.<\/span><\/p>\n<p><span style=\"color: rgb(102, 102, 102); line-height: 22px; font-family: georgia; font-size: 15px;\"><strong><a href=\"http:\/\/nakaya.org\/en\/review.aspx?id=417&#038;type=body\" target=\"_blank\" rel=\"noopener noreferrer\">Hojas de oto\u00f1o &#8211; Tame-Sukashi en dos capas<\/a><\/strong>.  Precio : $ 2.800<\/span><\/p>\n<p><span style=\"color: rgb(102, 102, 102); line-height: 22px; font-family: georgia; font-size: 15px;\">A pedido del cliente, se incorporan las hojas que aparecen verticalmente entre la tapa y el cuerpo.<\/span><\/p>\n<p><span style=\"color: rgb(102, 102, 102); line-height: 22px; font-family: georgia; font-size: 15px;\"><strong><a href=\"https:\/\/www.pinterest.com\/pin\/28921622584731345\/\" target=\"_blank\" rel=\"noopener noreferrer\">Chain Mail <\/a>(estilo Armadura) &#8211; IV &#8211; Twist<\/strong>.  Precio: $ 1,650.00<\/span><\/p>\n<p><span style=\"color: rgb(102, 102, 102); line-height: 22px; font-family: georgia; font-size: 15px;\">Una variaci\u00f3n del Chain Mail III, El Chain Mail IV adquiere una forma diferente de tejido anillado usando un estilo llamado Trinitymaille. Este m\u00e9todo conecta tres anillados en uno, creando una forma de tri\u00e1ngulo<\/span><span style=\"color: rgb(102, 102, 102); line-height: 22px; font-family: georgia; font-size: 15px;\">.<\/span><span style=\"color: rgb(0, 174, 239); line-height: 22px; font-family: georgia; font-size: 18px;\"> \u25a0<\/span><\/p>\n<p><\/span><\/p>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>Cada estilogr\u00e1fica Nakaya requiere un m\u00ednimo de tres a seis meses para su fabricaci\u00f3n.<\/p>\n","protected":false},"author":139,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[6233],"tags":[],"class_list":["post-21226","post","type-post","status-publish","format-standard","hentry","category-regalos","category-6233","description-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Estilogr\u00e1ficas de lujo Nakaya: \u201cS\u00f3lo para su mano\u201d - AzureAzure.com<\/title>\n<meta name=\"description\" content=\"Cada estilogr\u00e1fica Nakaya requiere un m\u00ednimo de tres a seis meses para su fabricaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.azureazure.com\/es\/regalos\/plumas-nakaya\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estilogr\u00e1ficas de lujo Nakaya: \u201cS\u00f3lo para su mano\u201d\" \/>\n<meta property=\"og:description\" content=\"Cada estilogr\u00e1fica Nakaya requiere un m\u00ednimo de tres a seis meses para su fabricaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.azureazure.com\/es\/regalos\/plumas-nakaya\/\" \/>\n<meta property=\"og:site_name\" content=\"AzureAzure.com\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-29T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-12T13:29:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.azureazure.com\/files\/Images\/Bulletins\/SpecialToys\/nakaya-pens\/Artboard%2010.jpg\" \/>\n<meta name=\"author\" content=\"Rick Stedman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rick Stedman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.azureazure.com\\\/es\\\/regalos\\\/plumas-nakaya\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.azureazure.com\\\/es\\\/regalos\\\/plumas-nakaya\\\/\"},\"author\":{\"name\":\"Rick Stedman\",\"@id\":\"https:\\\/\\\/www.azureazure.com\\\/es\\\/#\\\/schema\\\/person\\\/af30357e069811156f098462e64acaca\"},\"headline\":\"Estilogr\u00e1ficas de lujo Nakaya: \u201cS\u00f3lo para su mano\u201d\",\"datePublished\":\"2016-04-29T00:00:00+00:00\",\"dateModified\":\"2019-11-12T13:29:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.azureazure.com\\\/es\\\/regalos\\\/plumas-nakaya\\\/\"},\"wordCount\":585,\"commentCount\":0,\"articleSection\":[\"Regalos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.azureazure.com\\\/es\\\/regalos\\\/plumas-nakaya\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.azureazure.com\\\/es\\\/regalos\\\/plumas-nakaya\\\/\",\"url\":\"https:\\\/\\\/www.azureazure.com\\\/es\\\/regalos\\\/plumas-nakaya\\\/\",\"name\":\"Estilogr\u00e1ficas de lujo Nakaya: \u201cS\u00f3lo para su mano\u201d - AzureAzure.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.azureazure.com\\\/es\\\/#website\"},\"datePublished\":\"2016-04-29T00:00:00+00:00\",\"dateModified\":\"2019-11-12T13:29:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.azureazure.com\\\/es\\\/#\\\/schema\\\/person\\\/af30357e069811156f098462e64acaca\"},\"description\":\"Cada estilogr\u00e1fica Nakaya requiere un m\u00ednimo de tres a seis meses para su fabricaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.azureazure.com\\\/es\\\/regalos\\\/plumas-nakaya\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.azureazure.com\\\/es\\\/regalos\\\/plumas-nakaya\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.azureazure.com\\\/es\\\/regalos\\\/plumas-nakaya\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.azureazure.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estilogr\u00e1ficas de lujo Nakaya: \u201cS\u00f3lo para su mano\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.azureazure.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.azureazure.com\\\/es\\\/\",\"name\":\"AzureAzure.com\",\"description\":\"Luxury Global Magazine\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.azureazure.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.azureazure.com\\\/es\\\/#\\\/schema\\\/person\\\/af30357e069811156f098462e64acaca\",\"name\":\"Rick Stedman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81add578797b084d23bd941173248a42a4048e6d64065d120a8925e0d632edad?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81add578797b084d23bd941173248a42a4048e6d64065d120a8925e0d632edad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81add578797b084d23bd941173248a42a4048e6d64065d120a8925e0d632edad?s=96&d=mm&r=g\",\"caption\":\"Rick Stedman\"},\"url\":\"https:\\\/\\\/www.azureazure.com\\\/es\\\/author\\\/rick-stedman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Estilogr\u00e1ficas de lujo Nakaya: \u201cS\u00f3lo para su mano\u201d - AzureAzure.com","description":"Cada estilogr\u00e1fica Nakaya requiere un m\u00ednimo de tres a seis meses para su fabricaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.azureazure.com\/es\/regalos\/plumas-nakaya\/","og_locale":"es_ES","og_type":"article","og_title":"Estilogr\u00e1ficas de lujo Nakaya: \u201cS\u00f3lo para su mano\u201d","og_description":"Cada estilogr\u00e1fica Nakaya requiere un m\u00ednimo de tres a seis meses para su fabricaci\u00f3n.","og_url":"https:\/\/www.azureazure.com\/es\/regalos\/plumas-nakaya\/","og_site_name":"AzureAzure.com","article_published_time":"2016-04-29T00:00:00+00:00","article_modified_time":"2019-11-12T13:29:24+00:00","og_image":[{"url":"https:\/\/www.azureazure.com\/files\/Images\/Bulletins\/SpecialToys\/nakaya-pens\/Artboard%2010.jpg","type":"","width":"","height":""}],"author":"Rick Stedman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Rick Stedman","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.azureazure.com\/es\/regalos\/plumas-nakaya\/#article","isPartOf":{"@id":"https:\/\/www.azureazure.com\/es\/regalos\/plumas-nakaya\/"},"author":{"name":"Rick Stedman","@id":"https:\/\/www.azureazure.com\/es\/#\/schema\/person\/af30357e069811156f098462e64acaca"},"headline":"Estilogr\u00e1ficas de lujo Nakaya: \u201cS\u00f3lo para su mano\u201d","datePublished":"2016-04-29T00:00:00+00:00","dateModified":"2019-11-12T13:29:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.azureazure.com\/es\/regalos\/plumas-nakaya\/"},"wordCount":585,"commentCount":0,"articleSection":["Regalos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.azureazure.com\/es\/regalos\/plumas-nakaya\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.azureazure.com\/es\/regalos\/plumas-nakaya\/","url":"https:\/\/www.azureazure.com\/es\/regalos\/plumas-nakaya\/","name":"Estilogr\u00e1ficas de lujo Nakaya: \u201cS\u00f3lo para su mano\u201d - AzureAzure.com","isPartOf":{"@id":"https:\/\/www.azureazure.com\/es\/#website"},"datePublished":"2016-04-29T00:00:00+00:00","dateModified":"2019-11-12T13:29:24+00:00","author":{"@id":"https:\/\/www.azureazure.com\/es\/#\/schema\/person\/af30357e069811156f098462e64acaca"},"description":"Cada estilogr\u00e1fica Nakaya requiere un m\u00ednimo de tres a seis meses para su fabricaci\u00f3n.","breadcrumb":{"@id":"https:\/\/www.azureazure.com\/es\/regalos\/plumas-nakaya\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.azureazure.com\/es\/regalos\/plumas-nakaya\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.azureazure.com\/es\/regalos\/plumas-nakaya\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.azureazure.com\/es\/"},{"@type":"ListItem","position":2,"name":"Estilogr\u00e1ficas de lujo Nakaya: \u201cS\u00f3lo para su mano\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.azureazure.com\/es\/#website","url":"https:\/\/www.azureazure.com\/es\/","name":"AzureAzure.com","description":"Luxury Global Magazine","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.azureazure.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.azureazure.com\/es\/#\/schema\/person\/af30357e069811156f098462e64acaca","name":"Rick Stedman","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/81add578797b084d23bd941173248a42a4048e6d64065d120a8925e0d632edad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/81add578797b084d23bd941173248a42a4048e6d64065d120a8925e0d632edad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81add578797b084d23bd941173248a42a4048e6d64065d120a8925e0d632edad?s=96&d=mm&r=g","caption":"Rick Stedman"},"url":"https:\/\/www.azureazure.com\/es\/author\/rick-stedman\/"}]}},"_links":{"self":[{"href":"https:\/\/www.azureazure.com\/es\/wp-json\/wp\/v2\/posts\/21226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.azureazure.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.azureazure.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.azureazure.com\/es\/wp-json\/wp\/v2\/users\/139"}],"replies":[{"embeddable":true,"href":"https:\/\/www.azureazure.com\/es\/wp-json\/wp\/v2\/comments?post=21226"}],"version-history":[{"count":0,"href":"https:\/\/www.azureazure.com\/es\/wp-json\/wp\/v2\/posts\/21226\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.azureazure.com\/es\/wp-json\/wp\/v2\/media?parent=21226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.azureazure.com\/es\/wp-json\/wp\/v2\/categories?post=21226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.azureazure.com\/es\/wp-json\/wp\/v2\/tags?post=21226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}